{"id":7668,"date":"2024-06-07T10:12:28","date_gmt":"2024-06-07T08:12:28","guid":{"rendered":"https:\/\/www.hotellalla.com\/?post_type=offer&#038;p=7668"},"modified":"2026-04-13T11:29:11","modified_gmt":"2026-04-13T09:29:11","slug":"ironman-italy-emilia-romagna-triathlon","status":"publish","type":"offer","link":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/","title":{"rendered":"Ironman Italy Emilia Romagna"},"content":{"rendered":"<div  class=\"grids-section grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:3\/7;--_ga-row:2\/6;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p>Hotel per IRONMAN Emilia Romagna \u2013 Offerta Speciale per Triatleti<\/p>\n\n\n\n<p>A settembre torna uno degli eventi sportivi pi\u00f9 attesi al mondo: <strong>IRONMAN Emilia Romagna<\/strong>, con oltre 3.000 partecipanti provenienti da ogni nazione pronti a sfidarsi nella splendida cornice della Riviera Romagnola.<\/p>\n\n\n\n<p>Se cerchi un <strong>hotel per IRONMAN a Cesenatico<\/strong>, il nostro pacchetto dedicato ai triatleti \u00e8 la soluzione ideale per vivere la gara con il massimo comfort e servizi su misura.<\/p>\n\n\n\n\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Il nostro Pacchetto IRONMAN include:<\/h2>\n\n\n\n<p>\u2714 Porta la tua bici direttamente in camera<br>\u2714 Prima colazione rinforzata dolce e salata, anticipata alle prime ore del mattino il giorno della gara<br>\u2714 Wi-Fi gratuito per condividere ogni emozione<br>\u2714 Posto auto riservato a 200 metri dall\u2019hotel (fino a esaurimento)<br>\u2714 Utilizzo della palestra con attrezzature Technogym<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Servizi Extra su Prenotazione per Atleti IRONMAN<\/h2>\n\n\n\n<p>Per prepararti al meglio alla gara o recuperare dopo la competizione, offriamo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Massaggi rilassanti e defaticanti direttamente in camera<\/li>\n\n\n\n<li>Allenamento in piscina con ingresso esclusivo dalle 7:00 alle 9:00<\/li>\n\n\n\n<li>Pranzo e cena con men\u00f9 personalizzati e salutari per sportivi<\/li>\n\n\n\n<li>Servizio lavaggio indumenti tecnici<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Scegli il nostro <strong>hotel per triatleti durante IRONMAN Emilia Romagna<\/strong> e vivi un soggiorno studiato per le esigenze di chi ama lo sport, la performance e il recupero ottimale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prenota ora la tua offerta IRONMAN a Cesenatico<\/h3>\n\n\n\n<p>Preparati alla gara in totale tranquillit\u00e0 e assicurati la migliore tariffa disponibile.<\/p>\n\n\n\n<p><em>Tassa di soggiorno esclusa.<\/em><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<a href=\"https:\/\/reservations.verticalbooking.com\/premium\/index_pacchetti.html?id_albergo=10887&dc=110&id_stile=16673&lingua_int=ita\" class=\"btn btn-booking\" target=\"_blank\">Prenota ora<\/a>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<\/div>\n\n<div class=\"grids-area\" style=\"--_ga-column:8\/11;--_ga-row:2\/6;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n    <div class=\"custom-gallery-wrapper custom-gallery-wrapper-column-1\">\n                <span class=\"enable-fullscreen\" onclick=\"showHideFotorama('custom-gallery_1', 0);\">\n            <i class=\"far fa-expand\"><\/i>\n        <\/span>\n                                        <figure class=\"full-width gallery-wrapper-image gallery-wrapper-image-0\" onclick=\"showHideFotorama('custom-gallery_1', 0);\">\n                <img decoding=\"async\" class=\"gallery-wrapper-image-small\" src=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-corridoio-con-una-parete-rossa.webp\">\n            <\/figure>\n                                    <\/div>\n\n    <div style=\"width:1px;height:1px;position:absolute;\" name=\"fotorama\" id=\"custom-gallery_1\" class=\"fotorama\" data-width=\"100%\"  data-nav=\"thumbs\"  data-allowfullscreen=\"true\" >\n                    <img decoding=\"async\" src=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-corridoio-con-una-parete-rossa.webp\" class=\"attachment-full skip-lazy\" \/>\n                    <img decoding=\"async\" src=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-piatto-di-cibo-2.webp\" class=\"attachment-full skip-lazy\" \/>\n                    <img decoding=\"async\" src=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/BLA09836.jpg\" class=\"attachment-full skip-lazy\" \/>\n                    <img decoding=\"async\" src=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/02\/superior-14.jpg\" class=\"attachment-full skip-lazy\" \/>\n                    <img decoding=\"async\" src=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/ALB09705.jpg\" class=\"attachment-full skip-lazy\" \/>\n                    <img decoding=\"async\" src=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/DJI_0111.jpg\" class=\"attachment-full skip-lazy\" \/>\n            <\/div>\n\n\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<\/div>\n<\/div><\/div>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SWIM BIKE RUN<\/p>\n","protected":false},"author":19,"featured_media":6986,"template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"offer_categories":[51],"class_list":["post-7668","offer","type-offer","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ironman Italy Emilia Romagna - Hotel Lalla Beauty &amp; Relax<\/title>\n<meta name=\"description\" content=\"La gara per eccellenza : NUOTO, BICI, MARATONA. I triatleti di tutto il mondo hanno trovato la localit\u00e0 perfetta per competere IRONMAN ITALY. Swim, bike, run.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ironman Italy Emilia Romagna - Hotel Lalla Beauty &amp; Relax\" \/>\n<meta property=\"og:description\" content=\"La gara per eccellenza : NUOTO, BICI, MARATONA. I triatleti di tutto il mondo hanno trovato la localit\u00e0 perfetta per competere IRONMAN ITALY. Swim, bike, run.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Lalla Beauty &amp; Relax\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T09:29:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/\",\"url\":\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/\",\"name\":\"Ironman Italy Emilia Romagna - Hotel Lalla Beauty &amp; Relax\",\"isPartOf\":{\"@id\":\"https:\/\/www.hotellalla.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp\",\"datePublished\":\"2024-06-07T08:12:28+00:00\",\"dateModified\":\"2026-04-13T09:29:11+00:00\",\"description\":\"La gara per eccellenza : NUOTO, BICI, MARATONA. I triatleti di tutto il mondo hanno trovato la localit\u00e0 perfetta per competere IRONMAN ITALY. Swim, bike, run.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#primaryimage\",\"url\":\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp\",\"contentUrl\":\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp\",\"width\":1280,\"height\":720,\"caption\":\"Un gruppo di persone in uniforme.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.hotellalla.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ironman Italy Emilia Romagna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hotellalla.com\/it\/#website\",\"url\":\"https:\/\/www.hotellalla.com\/it\/\",\"name\":\"Hotel Lalla Beauty &amp; Relax\",\"description\":\"Cesenatico\",\"publisher\":{\"@id\":\"https:\/\/www.hotellalla.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hotellalla.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hotellalla.com\/it\/#organization\",\"name\":\"Hotel Lalla Beauty &amp; Relax\",\"url\":\"https:\/\/www.hotellalla.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.hotellalla.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/05\/hotel-lalla.svg\",\"contentUrl\":\"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/05\/hotel-lalla.svg\",\"caption\":\"Hotel Lalla Beauty &amp; Relax\"},\"image\":{\"@id\":\"https:\/\/www.hotellalla.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ironman Italy Emilia Romagna - Hotel Lalla Beauty &amp; Relax","description":"La gara per eccellenza : NUOTO, BICI, MARATONA. I triatleti di tutto il mondo hanno trovato la localit\u00e0 perfetta per competere IRONMAN ITALY. Swim, bike, run.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/","og_locale":"it_IT","og_type":"article","og_title":"Ironman Italy Emilia Romagna - Hotel Lalla Beauty &amp; Relax","og_description":"La gara per eccellenza : NUOTO, BICI, MARATONA. I triatleti di tutto il mondo hanno trovato la localit\u00e0 perfetta per competere IRONMAN ITALY. Swim, bike, run.","og_url":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/","og_site_name":"Hotel Lalla Beauty &amp; Relax","article_modified_time":"2026-04-13T09:29:11+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/","url":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/","name":"Ironman Italy Emilia Romagna - Hotel Lalla Beauty &amp; Relax","isPartOf":{"@id":"https:\/\/www.hotellalla.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#primaryimage"},"image":{"@id":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp","datePublished":"2024-06-07T08:12:28+00:00","dateModified":"2026-04-13T09:29:11+00:00","description":"La gara per eccellenza : NUOTO, BICI, MARATONA. I triatleti di tutto il mondo hanno trovato la localit\u00e0 perfetta per competere IRONMAN ITALY. Swim, bike, run.","breadcrumb":{"@id":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#primaryimage","url":"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp","contentUrl":"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp","width":1280,"height":720,"caption":"Un gruppo di persone in uniforme."},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotellalla.com\/it\/offerta\/ironman-italy-emilia-romagna-triathlon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hotellalla.com\/it\/"},{"@type":"ListItem","position":2,"name":"Ironman Italy Emilia Romagna"}]},{"@type":"WebSite","@id":"https:\/\/www.hotellalla.com\/it\/#website","url":"https:\/\/www.hotellalla.com\/it\/","name":"Hotel Lalla Beauty &amp; Relax","description":"Cesenatico","publisher":{"@id":"https:\/\/www.hotellalla.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotellalla.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hotellalla.com\/it\/#organization","name":"Hotel Lalla Beauty &amp; Relax","url":"https:\/\/www.hotellalla.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hotellalla.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/05\/hotel-lalla.svg","contentUrl":"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/05\/hotel-lalla.svg","caption":"Hotel Lalla Beauty &amp; Relax"},"image":{"@id":"https:\/\/www.hotellalla.com\/it\/#\/schema\/logo\/image\/"}}]}},"featured_img":"https:\/\/www.hotellalla.com\/wp-content\/uploads\/2024\/06\/Un-gruppo-di-persone-in-uniforme.webp","coauthors":[],"author_meta":{"author_link":"https:\/\/www.hotellalla.com\/it\/author\/francesco\/","display_name":"Francesco"},"relative_dates":{"created":"Pubblicato 2 anni fa","modified":"Aggiornato 4 settimane fa"},"absolute_dates":{"created":"Pubblicato il 07\/06\/2024","modified":"Aggiornato il 13\/04\/2026"},"absolute_dates_time":{"created":"Pubblicato il 07\/06\/2024 10:12","modified":"Aggiornato il 13\/04\/2026 11:29"},"featured_img_caption":"Un gruppo di persone in uniforme.","tax_additional":{"offer_categories":{"linked":["<a href=\"https:\/\/www.hotellalla.com\/it\/offer_categories\/eventi\/\" class=\"advgb-post-tax-term\">Eventi<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Eventi<\/span>"],"slug":"offer_categories","name":"Categorie"},"translation_priority":{"linked":["<a href=\"https:\/\/www.hotellalla.com\/it\/?taxonomy=translation_priority&#038;term=opzionale\" class=\"advgb-post-tax-term\">Opzionale<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Opzionale<\/span>"],"slug":"translation_priority","name":"Priorit\u00e0 di Traduzione"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/offer\/7668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/offer"}],"about":[{"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/types\/offer"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/users\/19"}],"version-history":[{"count":18,"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/offer\/7668\/revisions"}],"predecessor-version":[{"id":10120,"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/offer\/7668\/revisions\/10120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/media\/6986"}],"wp:attachment":[{"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/media?parent=7668"}],"wp:term":[{"taxonomy":"offer_categories","embeddable":true,"href":"https:\/\/www.hotellalla.com\/it\/wp-json\/wp\/v2\/offer_categories?post=7668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}